{"id":1006,"date":"2024-06-25T15:56:31","date_gmt":"2024-06-25T13:56:31","guid":{"rendered":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/"},"modified":"2024-06-25T15:56:31","modified_gmt":"2024-06-25T13:56:31","slug":"the-earth-in-the-cosmos-20","status":"publish","type":"post","link":"https:\/\/ameliagalli.it\/en\/la-terra-nel-cosmo-20\/","title":{"rendered":"The Earth in the Cosmos 20"},"content":{"rendered":"<p>Our earthly landscapes are ever closer to the beauty of the cosmos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Our earthly landscapes are ever closer to the beauty of the cosmos.<\/p>","protected":false},"author":1,"featured_media":1005,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":{"dimensioni":"150 x 150","tecnica":"Olio e Acrilico su tela"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La Terra Nel Cosmo 20 - Scipona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ameliagalli.it\/en\/the-earth-in-the-cosmos-20\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Terra Nel Cosmo 20\" \/>\n<meta property=\"og:description\" content=\"Sono i nostri paesaggi terreni sempre piu&#8217; vicini alla bellezza del cosmo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ameliagalli.it\/en\/the-earth-in-the-cosmos-20\/\" \/>\n<meta property=\"og:site_name\" content=\"Scipona\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-25T13:56:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/logo_scipona.png\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ghostapp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ghostapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/\"},\"author\":{\"name\":\"ghostapp\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#\\\/schema\\\/person\\\/e42b1faf8e50f95eced728a95f793aae\"},\"headline\":\"La Terra Nel Cosmo 20\",\"datePublished\":\"2024-06-25T13:56:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/\"},\"wordCount\":16,\"image\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/La-Terra-Nel-Cosmo-20.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/\",\"url\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/\",\"name\":\"La Terra Nel Cosmo 20 - Scipona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/La-Terra-Nel-Cosmo-20.jpg\",\"datePublished\":\"2024-06-25T13:56:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#\\\/schema\\\/person\\\/e42b1faf8e50f95eced728a95f793aae\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/La-Terra-Nel-Cosmo-20.jpg\",\"contentUrl\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/La-Terra-Nel-Cosmo-20.jpg\",\"width\":937,\"height\":878},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/la-terra-nel-cosmo-20\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ameliagalli.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Terra Nel Cosmo 20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#website\",\"url\":\"https:\\\/\\\/ameliagalli.it\\\/\",\"name\":\"Scipona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ameliagalli.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#\\\/schema\\\/person\\\/e42b1faf8e50f95eced728a95f793aae\",\"name\":\"ghostapp\",\"sameAs\":[\"https:\\\/\\\/ameliagalli.it\"],\"url\":\"https:\\\/\\\/ameliagalli.it\\\/en\\\/author\\\/ghostapp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The Earth in the Cosmos 20 - Scipona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ameliagalli.it\/en\/the-earth-in-the-cosmos-20\/","og_locale":"en_US","og_type":"article","og_title":"La Terra Nel Cosmo 20","og_description":"Sono i nostri paesaggi terreni sempre piu&#8217; vicini alla bellezza del cosmo.","og_url":"https:\/\/ameliagalli.it\/en\/the-earth-in-the-cosmos-20\/","og_site_name":"Scipona","article_published_time":"2024-06-25T13:56:31+00:00","og_image":[{"width":320,"height":147,"url":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/logo_scipona.png","type":"image\/png"}],"author":"ghostapp","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ghostapp"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/#article","isPartOf":{"@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/"},"author":{"name":"ghostapp","@id":"https:\/\/ameliagalli.it\/#\/schema\/person\/e42b1faf8e50f95eced728a95f793aae"},"headline":"La Terra Nel Cosmo 20","datePublished":"2024-06-25T13:56:31+00:00","mainEntityOfPage":{"@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/"},"wordCount":16,"image":{"@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/#primaryimage"},"thumbnailUrl":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/La-Terra-Nel-Cosmo-20.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/","url":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/","name":"The Earth in the Cosmos 20 - Scipona","isPartOf":{"@id":"https:\/\/ameliagalli.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/#primaryimage"},"image":{"@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/#primaryimage"},"thumbnailUrl":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/La-Terra-Nel-Cosmo-20.jpg","datePublished":"2024-06-25T13:56:31+00:00","author":{"@id":"https:\/\/ameliagalli.it\/#\/schema\/person\/e42b1faf8e50f95eced728a95f793aae"},"breadcrumb":{"@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/#primaryimage","url":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/La-Terra-Nel-Cosmo-20.jpg","contentUrl":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/La-Terra-Nel-Cosmo-20.jpg","width":937,"height":878},{"@type":"BreadcrumbList","@id":"https:\/\/ameliagalli.it\/la-terra-nel-cosmo-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ameliagalli.it\/"},{"@type":"ListItem","position":2,"name":"La Terra Nel Cosmo 20"}]},{"@type":"WebSite","@id":"https:\/\/ameliagalli.it\/#website","url":"https:\/\/ameliagalli.it\/","name":"Scipona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ameliagalli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/ameliagalli.it\/#\/schema\/person\/e42b1faf8e50f95eced728a95f793aae","name":"ghostapp","sameAs":["https:\/\/ameliagalli.it"],"url":"https:\/\/ameliagalli.it\/en\/author\/ghostapp\/"}]}},"_links":{"self":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/posts\/1006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/comments?post=1006"}],"version-history":[{"count":0,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/posts\/1006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/media\/1005"}],"wp:attachment":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/media?parent=1006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/categories?post=1006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/tags?post=1006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}