{"id":1406,"date":"2024-07-02T23:16:20","date_gmt":"2024-07-02T21:16:20","guid":{"rendered":"https:\/\/ameliagalli.it\/?p=1406"},"modified":"2024-07-02T23:16:20","modified_gmt":"2024-07-02T21:16:20","slug":"immensity-of-the-sea","status":"publish","type":"post","link":"https:\/\/ameliagalli.it\/en\/limmensita-del-mare\/","title":{"rendered":"The immensity of the sea"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":{"dimensioni":"200 x 115","tecnica":"Olio su tela"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;immensita&#039; del mare - Scipona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ameliagalli.it\/en\/immensity-of-the-sea\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;immensita&#039; del mare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ameliagalli.it\/en\/immensity-of-the-sea\/\" \/>\n<meta property=\"og:site_name\" content=\"Scipona\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T21:16:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/07\/Limmensita-del-mare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ghostapp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ghostapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/\"},\"author\":{\"name\":\"ghostapp\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#\\\/schema\\\/person\\\/e42b1faf8e50f95eced728a95f793aae\"},\"headline\":\"L&#8217;immensita&#8217; del mare\",\"datePublished\":\"2024-07-02T21:16:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/\"},\"wordCount\":4,\"image\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Limmensita-del-mare.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/\",\"url\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/\",\"name\":\"L'immensita' del mare - Scipona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Limmensita-del-mare.jpg\",\"datePublished\":\"2024-07-02T21:16:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#\\\/schema\\\/person\\\/e42b1faf8e50f95eced728a95f793aae\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Limmensita-del-mare.jpg\",\"contentUrl\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Limmensita-del-mare.jpg\",\"width\":1500,\"height\":833},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/limmensita-del-mare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ameliagalli.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;immensita&#8217; del mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#website\",\"url\":\"https:\\\/\\\/ameliagalli.it\\\/\",\"name\":\"Scipona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ameliagalli.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#\\\/schema\\\/person\\\/e42b1faf8e50f95eced728a95f793aae\",\"name\":\"ghostapp\",\"sameAs\":[\"https:\\\/\\\/ameliagalli.it\"],\"url\":\"https:\\\/\\\/ameliagalli.it\\\/en\\\/author\\\/ghostapp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The immensity of the sea - Scipona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ameliagalli.it\/en\/immensity-of-the-sea\/","og_locale":"en_US","og_type":"article","og_title":"L'immensita' del mare","og_url":"https:\/\/ameliagalli.it\/en\/immensity-of-the-sea\/","og_site_name":"Scipona","article_published_time":"2024-07-02T21:16:20+00:00","og_image":[{"width":1500,"height":833,"url":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/07\/Limmensita-del-mare.jpg","type":"image\/jpeg"}],"author":"ghostapp","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ghostapp"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/#article","isPartOf":{"@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/"},"author":{"name":"ghostapp","@id":"https:\/\/ameliagalli.it\/#\/schema\/person\/e42b1faf8e50f95eced728a95f793aae"},"headline":"L&#8217;immensita&#8217; del mare","datePublished":"2024-07-02T21:16:20+00:00","mainEntityOfPage":{"@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/"},"wordCount":4,"image":{"@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/#primaryimage"},"thumbnailUrl":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/07\/Limmensita-del-mare.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/","url":"https:\/\/ameliagalli.it\/limmensita-del-mare\/","name":"The immensity of the sea - Scipona","isPartOf":{"@id":"https:\/\/ameliagalli.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/#primaryimage"},"image":{"@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/#primaryimage"},"thumbnailUrl":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/07\/Limmensita-del-mare.jpg","datePublished":"2024-07-02T21:16:20+00:00","author":{"@id":"https:\/\/ameliagalli.it\/#\/schema\/person\/e42b1faf8e50f95eced728a95f793aae"},"breadcrumb":{"@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ameliagalli.it\/limmensita-del-mare\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/#primaryimage","url":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/07\/Limmensita-del-mare.jpg","contentUrl":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/07\/Limmensita-del-mare.jpg","width":1500,"height":833},{"@type":"BreadcrumbList","@id":"https:\/\/ameliagalli.it\/limmensita-del-mare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ameliagalli.it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;immensita&#8217; del mare"}]},{"@type":"WebSite","@id":"https:\/\/ameliagalli.it\/#website","url":"https:\/\/ameliagalli.it\/","name":"Scipona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ameliagalli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/ameliagalli.it\/#\/schema\/person\/e42b1faf8e50f95eced728a95f793aae","name":"ghostapp","sameAs":["https:\/\/ameliagalli.it"],"url":"https:\/\/ameliagalli.it\/en\/author\/ghostapp\/"}]}},"_links":{"self":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/posts\/1406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/comments?post=1406"}],"version-history":[{"count":0,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/posts\/1406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/media\/1418"}],"wp:attachment":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/media?parent=1406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/categories?post=1406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/tags?post=1406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}