{"id":928,"date":"2024-06-25T15:54:51","date_gmt":"2024-06-25T13:54:51","guid":{"rendered":"https:\/\/ameliagalli.it\/il-trasporto-1\/"},"modified":"2024-06-25T15:54:51","modified_gmt":"2024-06-25T13:54:51","slug":"transport-1","status":"publish","type":"post","link":"https:\/\/ameliagalli.it\/en\/il-trasporto-1\/","title":{"rendered":"The Transport 1"},"content":{"rendered":"<p>A heart, perhaps too big for that small vessel that carries it from one place to another.<\/p>","protected":false},"excerpt":{"rendered":"<p>A heart, perhaps too big for that small vessel that carries it from one place to another.<\/p>","protected":false},"author":1,"featured_media":927,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":{"dimensioni":"152 x 150","tecnica":"Olio su tela"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il Trasporto 1 - Scipona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ameliagalli.it\/en\/transport-1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Trasporto 1\" \/>\n<meta property=\"og:description\" content=\"Un cuore, forse troppo grande per quella piccola imbarcazione che lo porta da un luogo a un altro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ameliagalli.it\/en\/transport-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Scipona\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-25T13:54:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/logo_scipona.png\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ghostapp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ghostapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/\"},\"author\":{\"name\":\"ghostapp\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#\\\/schema\\\/person\\\/e42b1faf8e50f95eced728a95f793aae\"},\"headline\":\"Il Trasporto 1\",\"datePublished\":\"2024-06-25T13:54:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/\"},\"wordCount\":20,\"image\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Il-Trasporto-1.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/\",\"url\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/\",\"name\":\"Il Trasporto 1 - Scipona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Il-Trasporto-1.jpg\",\"datePublished\":\"2024-06-25T13:54:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#\\\/schema\\\/person\\\/e42b1faf8e50f95eced728a95f793aae\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Il-Trasporto-1.jpg\",\"contentUrl\":\"https:\\\/\\\/ameliagalli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Il-Trasporto-1.jpg\",\"width\":1000,\"height\":969},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/il-trasporto-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ameliagalli.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Trasporto 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#website\",\"url\":\"https:\\\/\\\/ameliagalli.it\\\/\",\"name\":\"Scipona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ameliagalli.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ameliagalli.it\\\/#\\\/schema\\\/person\\\/e42b1faf8e50f95eced728a95f793aae\",\"name\":\"ghostapp\",\"sameAs\":[\"https:\\\/\\\/ameliagalli.it\"],\"url\":\"https:\\\/\\\/ameliagalli.it\\\/en\\\/author\\\/ghostapp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transport 1 - Scipona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ameliagalli.it\/en\/transport-1\/","og_locale":"en_US","og_type":"article","og_title":"Il Trasporto 1","og_description":"Un cuore, forse troppo grande per quella piccola imbarcazione che lo porta da un luogo a un altro.","og_url":"https:\/\/ameliagalli.it\/en\/transport-1\/","og_site_name":"Scipona","article_published_time":"2024-06-25T13:54:51+00:00","og_image":[{"width":320,"height":147,"url":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/logo_scipona.png","type":"image\/png"}],"author":"ghostapp","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ghostapp"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/#article","isPartOf":{"@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/"},"author":{"name":"ghostapp","@id":"https:\/\/ameliagalli.it\/#\/schema\/person\/e42b1faf8e50f95eced728a95f793aae"},"headline":"Il Trasporto 1","datePublished":"2024-06-25T13:54:51+00:00","mainEntityOfPage":{"@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/"},"wordCount":20,"image":{"@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/#primaryimage"},"thumbnailUrl":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/Il-Trasporto-1.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/","url":"https:\/\/ameliagalli.it\/il-trasporto-1\/","name":"Transport 1 - Scipona","isPartOf":{"@id":"https:\/\/ameliagalli.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/#primaryimage"},"image":{"@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/#primaryimage"},"thumbnailUrl":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/Il-Trasporto-1.jpg","datePublished":"2024-06-25T13:54:51+00:00","author":{"@id":"https:\/\/ameliagalli.it\/#\/schema\/person\/e42b1faf8e50f95eced728a95f793aae"},"breadcrumb":{"@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ameliagalli.it\/il-trasporto-1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/#primaryimage","url":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/Il-Trasporto-1.jpg","contentUrl":"https:\/\/ameliagalli.it\/wp-content\/uploads\/2024\/06\/Il-Trasporto-1.jpg","width":1000,"height":969},{"@type":"BreadcrumbList","@id":"https:\/\/ameliagalli.it\/il-trasporto-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ameliagalli.it\/"},{"@type":"ListItem","position":2,"name":"Il Trasporto 1"}]},{"@type":"WebSite","@id":"https:\/\/ameliagalli.it\/#website","url":"https:\/\/ameliagalli.it\/","name":"Scipona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ameliagalli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/ameliagalli.it\/#\/schema\/person\/e42b1faf8e50f95eced728a95f793aae","name":"ghostapp","sameAs":["https:\/\/ameliagalli.it"],"url":"https:\/\/ameliagalli.it\/en\/author\/ghostapp\/"}]}},"_links":{"self":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/posts\/928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/comments?post=928"}],"version-history":[{"count":0,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/posts\/928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/media\/927"}],"wp:attachment":[{"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/media?parent=928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/categories?post=928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ameliagalli.it\/en\/wp-json\/wp\/v2\/tags?post=928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}